{"id":15591,"date":"2025-12-05T18:36:18","date_gmt":"2025-12-05T17:36:18","guid":{"rendered":"https:\/\/medigames.com\/?page_id=15591"},"modified":"2026-07-17T15:59:09","modified_gmt":"2026-07-17T13:59:09","slug":"pula-medulin-duplication","status":"publish","type":"page","link":"https:\/\/medigames.com\/es\/pula-medulin-duplication\/","title":{"rendered":"Oferta de patrocino"},"content":{"rendered":"<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-color uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-66700cc3 uagb-columns__columns-1 uagb-columns__max_width-custom fondbloc\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-6fc63d7c\"><div class=\"uagb-column__overlay\"><\/div>\n<h2 class=\"wp-block-heading has-text-align-center\">Consigue recompensas por invitar a tus amigos a Medigames 2027<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">MEDIGAMES es, ante todo, una aventura humana en la que se dan la mano el deporte, la salud y la amistad. Los mejores recuerdos se crean junto a otras personas, as\u00ed que, \u00bfpor qu\u00e9 no invitas a tus amigos o compa\u00f1eros de trabajo a que te acompa\u00f1en a Espa\u00f1a?<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"color:#b91414\"><strong>Por cada nuevo participante que patrocine, recibir\u00e1 un descuento de 75 \u20ac en su paquete de hotel MEDIGAMES.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Condiciones:<\/strong><br>\u2022 Oferta v\u00e1lida solo para participantes que reserven el paquete oficial del hotel.<br>\u2022 No acumulable con otras ofertas (estudiantes, grupos, etc.).<br>\u2022 La persona recomendada debe ser un nuevo participante en Medigames.<br>\u00a1Comparte, patrocina, ahorra!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te guardes los Medigames para ti solo: \u00a1invita a tus compa\u00f1eros, ayuda a hacer crecer la comunidad y disfruta de las recompensas!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div><\/section>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"944\" src=\"https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/ArgentiBraz-1024x944.png\" alt=\"\" class=\"wp-image-15592\" style=\"width:591px;height:auto\" srcset=\"https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/ArgentiBraz-1024x944.png 1024w, https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/ArgentiBraz-300x277.png 300w, https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/ArgentiBraz-768x708.png 768w, https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/ArgentiBraz-13x12.png 13w, https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/ArgentiBraz.png 1030w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-fef9e83c alignfull uagb-is-root-container\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"191\" src=\"https:\/\/medigames.com\/wp-content\/uploads\/2026\/08\/LogoNucia.png\" alt=\"\" class=\"wp-image-17121\" style=\"width:auto;height:90px\" srcset=\"https:\/\/medigames.com\/wp-content\/uploads\/2026\/08\/LogoNucia.png 597w, https:\/\/medigames.com\/wp-content\/uploads\/2026\/08\/LogoNucia-300x96.png 300w, https:\/\/medigames.com\/wp-content\/uploads\/2026\/08\/LogoNucia-18x6.png 18w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/medigames.com\/wp-content\/uploads\/2025\/10\/LogoMedCanadiens.png\" alt=\"\" style=\"width:auto;height:100px\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/medigames.com\/wp-content\/uploads\/2021\/10\/bauerfeind.png\" alt=\"\" style=\"width:auto;height:40px\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/medigames.com\/wp-content\/uploads\/2025\/12\/LogoVLVHorizon.png\" alt=\"\" style=\"width:auto;height:70px\"\/><\/figure>\n<\/div>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Consigue recompensas por invitar a tus amigos a Medigames 2027. MEDIGAMES es, ante todo, una aventura humana en la que el deporte, la salud y\u2026<\/p>","protected":false},"author":5,"featured_media":17092,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-15591","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666.jpg",2560,1400,false],"thumbnail":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-150x150.jpg",150,150,true],"medium":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-300x164.jpg",300,164,true],"medium_large":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-768x420.jpg",580,317,true],"large":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-1024x560.jpg",580,317,true],"1536x1536":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-1536x840.jpg",1536,840,true],"2048x2048":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-2048x1120.jpg",2048,1120,true],"trp-custom-language-flag":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-18x10.jpg",18,10,true],"post-thumbnail":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-1200x656.jpg",1200,656,true],"twentytwenty-fullscreen":["https:\/\/medigames.com\/wp-content\/uploads\/2026\/07\/P1000603-2-scaled-e1784296728666-1980x1083.jpg",1980,1083,true]},"uagb_author_info":{"display_name":"mediAdmin","author_link":"https:\/\/medigames.com\/es\/author\/mediadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"Be rewarded to invite your friends to Medigames 2027 MEDIGAMES is above all a human adventure where sport, health and&hellip;","_links":{"self":[{"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/pages\/15591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/comments?post=15591"}],"version-history":[{"count":4,"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/pages\/15591\/revisions"}],"predecessor-version":[{"id":17095,"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/pages\/15591\/revisions\/17095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/media\/17092"}],"wp:attachment":[{"href":"https:\/\/medigames.com\/es\/wp-json\/wp\/v2\/media?parent=15591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}